{"id":169949,"date":"2025-04-18T06:49:42","date_gmt":"2025-04-18T05:49:42","guid":{"rendered":"https:\/\/outsidergaming.com\/les-meilleurs-jeux-gothiques-du-sud-a-jouer-en-2025-marecages-secrets-et-esprits\/"},"modified":"2025-04-18T07:14:13","modified_gmt":"2025-04-18T06:14:13","slug":"les-meilleurs-jeux-gothiques-du-sud-a-jouer-en-2025-marecages-secrets-et-esprits","status":"publish","type":"post","link":"https:\/\/outsidergaming.com\/fr\/les-meilleurs-jeux-gothiques-du-sud-a-jouer-en-2025-marecages-secrets-et-esprits\/","title":{"rendered":"Les Meilleurs Jeux Gothiques du Sud \u00e0 Jouer en 2025 : Mar\u00e9cages, Secrets et Esprits"},"content":{"rendered":"<div class=\"wp-block-rank-math-toc-block\" id=\"rank-math-toc\">\n<h2>Table des mati\u00e8res<\/h2>\n<nav>\n<ul>\n<li><a href=\"#10-into-the-dead-our-darkest-days-2025\">10. Into the Dead: Our Darkest Days (2025)<\/a><\/li>\n<li><a href=\"#9-mafia-iii-2016\">9. Mafia III (2016)<\/a><\/li>\n<li><a href=\"#7-alone-in-the-dark-2024\">7. Alone in the Dark (2024)<\/a><\/li>\n<li><a href=\"#6-kentucky-route-zero-2020\">6. Kentucky Route Zero (2020)<\/a><\/li>\n<li><a href=\"#5-red-dead-redemption-2-2018\">5. Red Dead Redemption 2 (2018)<\/a><\/li>\n<li><a href=\"#4-scarlet-hollow-2021-ongoing\">4. Scarlet Hollow (2021 &#8211; En cours)<\/a><\/li>\n<li><a href=\"#3-resident-evil-7-biohazard-2017\">3. Resident Evil 7: Biohazard (2017)<\/a><\/li>\n<li><a href=\"#2-norco-2022\">2. Norco (2022)<\/a><\/li>\n<li><a href=\"#1-south-of-midnight-2025\">1. South of Midnight (2025)<\/a><\/li>\n<li><a href=\"#closing-the-screen-door-gently\">Fermer doucement la porte moustiquaire\u2026<\/a><\/li>\n<li><a href=\"#faq-best-southern-gothic-games\">FAQ : Meilleurs jeux gothiques du Sud<\/a>\n<ul><\/ul>\n<\/li>\n<\/ul>\n<\/nav>\n<\/div>\n<p>Les histoires gothiques du sud sont imbib\u00e9es de sueur, de superstition et de chagrin. Elles tordent l&rsquo;Am\u00e9rique famili\u00e8re en quelque chose d&rsquo;ombreux et d&rsquo;\u00e9trange\u2014o\u00f9 le papier peint qui s&rsquo;\u00e9caille cache des secrets de famille, o\u00f9 les cigales crient plus fort que le silence entre de vieux amis, et o\u00f9 le diable pourrait bien porter des souliers de \u00e9glise. Dans le monde du jeu vid\u00e9o, ce genre n&rsquo;inonde pas le march\u00e9, mais quand il appara\u00eet sous la forme d&rsquo;un bon jeu, il <em>s&rsquo;imbibe<\/em> d&rsquo;une ambiance particuli\u00e8re. Et en 2025, que vous ayez envie de plantations en d\u00e9composition, de myst\u00e8res de petite ville ou de frayeurs frites, il n&rsquo;y a jamais eu de meilleur moment pour explorer les meilleurs jeux gothiques du Sud.<\/p>\n<p>Des point-and-click pixelis\u00e9s aux horreurs \u00e0 succ\u00e8s et aux aventures narratives mystiques, voici dix titres remarquables\u2014class\u00e9s du grand \u00e0 l&rsquo;inoubliable\u2014qui capturent l&rsquo;esprit inqui\u00e9tant de la tradition gothique du Sud.<\/p>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<h3 class=\"wp-block-heading\" id=\"10-into-the-dead-our-darkest-days-2025\"><strong>10. Into the Dead: Our Darkest Days (2025)<\/strong><\/h3>\n<p><em>Plateforme : PC<\/em><\/p>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/into-the-dead-our-darkest-days-1.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/into-the-dead-our-darkest-days-1.jpg\" alt=\"Une capture d'\u00e9cran de Into the Dead: Our Darkest Days\" class=\"wp-image-169846\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/into-the-dead-our-darkest-days-1.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/into-the-dead-our-darkest-days-1-768x432.jpg.webp 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/into-the-dead-our-darkest-days-1-150x84.jpg 150w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/into-the-dead-our-darkest-days-1-300x169.jpg 300w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/into-the-dead-our-darkest-days-1-696x392.jpg.webp 696w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/into-the-dead-our-darkest-days-1-1068x601.jpg.webp 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">PikPok, Boltray Games<\/figcaption><\/figure>\n<p><\/a><\/div>\n<p><em><a href=\"https:\/\/store.steampowered.com\/app\/2239710\/Into_the_Dead_Our_Darkest_Days\/\" target=\"_blank\" rel=\"noopener\">Into the Dead: Our Darkest Days<\/a><\/em> est un jeu de survie en 2.5D d\u00e9filant sur le c\u00f4t\u00e9, se d\u00e9roulant au Texas des ann\u00e9es 1980, o\u00f9 une chaleur \u00e9crasante et un effondrement \u00e9conomique servent de toile de fond \u00e0 une \u00e9pid\u00e9mie de zombies implacable. M\u00e9langeant furtivit\u00e9 tendue, gestion brutale des ressources et strat\u00e9gie bas\u00e9e sur des abris, le jeu demande aux joueurs de guider un groupe de gens ordinaires \u00e0 travers un paysage urbain en ruine hant\u00e9 non seulement par les morts-vivants, mais aussi par le chagrin, la culpabilit\u00e9 et le d\u00e9sespoir.<\/p>\n<\/div>\n<\/div>\n<p>Bien qu&rsquo;il s&rsquo;agisse techniquement d&rsquo;un simulateur de survie zombie, son atmosph\u00e8re oppressante, son ambigu\u00eft\u00e9 morale et son r\u00e9cit \u00e0 combustion lente \u00e9voquent l&rsquo;essence du gothique du Sud : une soci\u00e9t\u00e9 bris\u00e9e s&rsquo;accrochant \u00e0 des structures en d\u00e9clin, \u00e0 la fois litt\u00e9rales et psychologiques. Avec ses rues embrum\u00e9es de chaleur, ses abris en d\u00e9composition et ses th\u00e8mes de perte et de pers\u00e9v\u00e9rance, <em>Into the Dead: Our Darkest Days<\/em> m\u00e9rite sa place parmi les meilleurs jeux gothiques du Sud de 2025\u2014non seulement pour ses attraits de genre, mais pour la fa\u00e7on dont il capture la d\u00e9cadence \u00e0 la fois du lieu et de la personne.<\/p>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"9-mafia-iii-2016\"><strong>9. Mafia III (2016)<\/strong><\/h3>\n<p><em>Plateforme : PC, PlayStation, Xbox<\/em><\/p>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/mafia-3-2.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"675\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/mafia-3-2.jpg\" alt=\"Une capture d'\u00e9cran de Mafia III\" class=\"wp-image-169837\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/mafia-3-2.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/mafia-3-2-768x480.jpg.webp 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/mafia-3-2-150x94.jpg 150w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/mafia-3-2-300x188.jpg.webp 300w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/mafia-3-2-696x435.jpg.webp 696w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/mafia-3-2-1068x668.jpg.webp 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">2K<\/figcaption><\/figure>\n<p><\/a><\/div>\n<p><em><a href=\"https:\/\/store.steampowered.com\/app\/360430\/Mafia_III_Definitive_Edition\/\" target=\"_blank\" rel=\"noopener\">Mafia III: Definitive Edition<\/a><\/em> est un drame criminel en monde ouvert se d\u00e9roulant dans les rues sulp\u00e9tres et en d\u00e9composition de New Bordeaux en 1968\u2014une Nouvelle-Orl\u00e9ans fictive impr\u00e9gn\u00e9e de tensions raciales, de traumatismes d&rsquo;apr\u00e8s-guerre et de la fa\u00e7ade en ruine de la civilit\u00e9 am\u00e9ricaine. Vous incarnez Lincoln Clay, un v\u00e9t\u00e9ran noir du Vietnam dont la famille de substitution est massacr\u00e9es par la mafia italienne, d\u00e9clenchant une campagne m\u00e9thodique et vengeresse pour d\u00e9manteler l&#8217;empire criminel morceau par morceau. Le gameplay tourne autour de la capture de quartiers de la ville, du recrutement de lieutenants et du choix de la fa\u00e7on de construire\u2014ou de trahir\u2014votre propre r\u00e9seau criminel, tout en naviguant dans un monde magnifiquement r\u00e9alis\u00e9, accompagn\u00e9 de rock et de soul des ann\u00e9es 60.<\/p>\n<\/div>\n<\/div>\n<p>Malgr\u00e9 son design de mission r\u00e9p\u00e9titif et son IA maladroite, <em>Mafia III<\/em> se distingue par sa puissante narration, son cadre richement dessin\u00e9 et son audacieuse critique sociale. Il m\u00e9rite une place dans notre liste de jeux gothiques du Sud pour la mani\u00e8re dont il tisse des th\u00e8mes de violence raciale, de pourriture spirituelle et de vengeance dans son architecture imbib\u00e9e de bayous et ses trottoirs tach\u00e9s de sang. Ce n&rsquo;est pas juste un jeu de mafia\u2014c&rsquo;est une complainte fun\u00e8bre pour le r\u00eave am\u00e9ricain, jou\u00e9e sur un jukebox cass\u00e9.<\/p>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"8-hunt-showdown-1896-2019\"><strong>8. Hunt: Showdown 1896 (2019)<\/strong><\/h2>\n<p><em>Plateforme : PC, PlayStation, Xbox<\/em><\/p>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/hunt-showdown-1896-1.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/hunt-showdown-1896-1.jpg\" alt=\"Une capture d'\u00e9cran de Hunt: Showdown 1896\" class=\"wp-image-169855\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/hunt-showdown-1896-1.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/hunt-showdown-1896-1-768x432.jpg.webp 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/hunt-showdown-1896-1-150x84.jpg 150w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/hunt-showdown-1896-1-300x169.jpg.webp 300w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/hunt-showdown-1896-1-696x392.jpg.webp 696w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/hunt-showdown-1896-1-1068x601.jpg.webp 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">Crytek<\/figcaption><\/figure>\n<p><\/a><\/div>\n<p><em><a href=\"https:\/\/store.steampowered.com\/app\/594650\/Hunt_Showdown_1896\/\" target=\"_blank\" rel=\"noopener\">Hunt: Showdown 1896<\/a><\/em> est un tireur d&rsquo;extraction brutal et atmosph\u00e9rique se d\u00e9roulant dans les mar\u00e9cages hant\u00e9s de la Louisiane du XIXe si\u00e8cle, o\u00f9 des plantations en d\u00e9composition et des bayous embrum\u00e9s cachent des monstres, des indices, et d&rsquo;autres chasseurs en qu\u00eate du m\u00eame prix. Le jeu plonge les joueurs\u2014en solo ou en \u00e9quipes\u2014dans des matchs o\u00f9 l&rsquo;objectif est de traquer et de tuer des boss surnaturels, de les bannir, et de s&rsquo;\u00e9chapper avec la prime avant que des joueurs rivaux ne vous abattent. La tension est implacable : un faux pas, un coup de feu r\u00e9sonnant, et soudain, toute la carte sait o\u00f9 vous \u00eates.<\/p>\n<\/div>\n<\/div>\n<p>La saveur gothique du Sud du jeu est profonde\u2014de l&rsquo;architecture glissante de boue et de la chaleur \u00e9touffante au paysage sonore inqui\u00e9tant des planchers qui craquent et des coups de feu lointains. Avec des m\u00e9caniques de mort permanente, des armes d&rsquo;un autre temps, et un sentiment de terreur omnipr\u00e9sent, <em>Hunt: Showdown 1896<\/em> concerne moins la victoire que la survie\u2014et ce poids psychologique est pr\u00e9cis\u00e9ment la raison pour laquelle il m\u00e9rite une place dans notre liste gothique du Sud. Ce n&rsquo;est pas juste un tireur ; c&rsquo;est un r\u00eave fi\u00e9vreux \u00e0 combustion lente r\u00e9gl\u00e9 sur le rythme des serpents \u00e0 sonnette et des cha\u00eenes rouill\u00e9es.<\/p>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"7-alone-in-the-dark-2024\"><strong>7. Alone in the Dark (2024)<\/strong><\/h3>\n<p><em>Plateforme : PC, PlayStation 5, Xbox Series X\/S<\/em><\/p>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/alone-in-the-dark-1.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/alone-in-the-dark-1.jpg\" alt=\"Une capture d'\u00e9cran de Alone in the Dark\" class=\"wp-image-169864\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/alone-in-the-dark-1.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/alone-in-the-dark-1-768x432.jpg.webp 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/alone-in-the-dark-1-150x84.jpg 150w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/alone-in-the-dark-1-300x169.jpg 300w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/alone-in-the-dark-1-696x392.jpg.webp 696w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/alone-in-the-dark-1-1068x601.jpg.webp 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">THQ Nordic<\/figcaption><\/figure>\n<p><\/a><\/div>\n<p><em><a href=\"https:\/\/store.steampowered.com\/app\/1310410\/Alone_in_the_Dark\/\" target=\"_blank\" rel=\"noopener\">Alone in the Dark<\/a><\/em> (2024) est une r\u00e9imagination moody du classique de 1992 qui a contribu\u00e9 \u00e0 fa\u00e7onner le genre de l&rsquo;horreur de survie. Se d\u00e9roulant dans la Louisiane des ann\u00e9es 1920, il s&rsquo;inspire profond\u00e9ment des traditions gothiques du Sud\u2014d\u00e9cadence, traumatisme, angoisse spirituelle\u2014le tout envelopp\u00e9 dans un conte lovecraftien de folie et de monstruosit\u00e9s. Les joueurs endossent les r\u00f4les d&rsquo;Emily Hartwood ou du d\u00e9tective priv\u00e9 Edward Carnby, explorant les halls inqui\u00e9tants du manoir Derceto et ses paysages de r\u00eave tordus dans une histoire \u00e9crite par Mikael Hedberg, l&rsquo;auteur de <em>SOMA<\/em> et <em>Amnesia<\/em>.<\/p>\n<\/div>\n<\/div>\n<p>Le gameplay \u00e9voque les racines de l&rsquo;horreur de survie classique avec un combat d\u00e9lib\u00e9r\u00e9ment maladroit et au rythme lent, des \u00e9nigmes environnementales et une progression ax\u00e9e sur l&rsquo;exploration\u2014bien que des probl\u00e8mes techniques et un rythme in\u00e9gal l&#8217;emp\u00eachent d&rsquo;atteindre la perfection. Pourtant, son atmosph\u00e8re cr\u00e9pusculaire, ses performances riches de Jodie Comer et David Harbour, et son effondrement psychologique lui valent une place l\u00e9gitime parmi les meilleurs jeux gothiques du Sud de l&rsquo;\u00e8re moderne.<\/p>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"6-kentucky-route-zero-2020\"><strong>6. Kentucky Route Zero (2020)<\/strong><\/h3>\n<p><em>Plateforme : PC, Consoles, Switch<\/em><\/p>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/kentucky-route-zero-1.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/kentucky-route-zero-1.jpg\" alt=\"Une capture d'\u00e9cran de Kentucky Route Zero\" class=\"wp-image-169873\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/kentucky-route-zero-1.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/kentucky-route-zero-1-768x432.jpg 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/kentucky-route-zero-1-150x84.jpg 150w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/kentucky-route-zero-1-300x169.jpg 300w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/kentucky-route-zero-1-696x392.jpg 696w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/kentucky-route-zero-1-1068x601.jpg.webp 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">Cardboard Computer<\/figcaption><\/figure>\n<p><\/a><\/div>\n<p><em><a href=\"https:\/\/store.steampowered.com\/app\/231200\/Kentucky_Route_Zero_PC_Edition\/\" target=\"_blank\" rel=\"noopener\">Kentucky Route Zero<\/a><\/em> est un jeu d&rsquo;aventure magique r\u00e9aliste qui \u00e9change les m\u00e9caniques de jeu traditionnelles contre une atmosph\u00e8re po\u00e9tique et une exp\u00e9rimentation narrative. Les joueurs voyagent avec un livreur fatigu\u00e9 nomm\u00e9 Conway le long d&rsquo;une autoroute secr\u00e8te et m\u00e9taphysique cach\u00e9e sous le Kentucky, rencontrant un casting inoubliable de vagabonds, de fant\u00f4mes et de r\u00eaveurs. Il n&rsquo;y a pas de puzzles, pas d&rsquo;\u00e9tats d&rsquo;\u00e9chec\u2014juste des choix de dialogue qui fa\u00e7onnent le ton du voyage plut\u00f4t que son issue.<\/p>\n<\/div>\n<\/div>\n<p>C&rsquo;est une exp\u00e9rience profond\u00e9ment th\u00e9\u00e2trale, souvent surr\u00e9aliste\u2014un m\u00e9lange \u00e9gal de lamentation gothique du Sud et de m\u00e9ditation tranquille sur la dette, la m\u00e9moire et la perte. Situ\u00e9 dans une Am\u00e9rique en d\u00e9composition de mines abandonn\u00e9es, de bureaucraties hant\u00e9es et de signaux radio en d\u00e9clin, le jeu \u00e9voque l&rsquo;\u00e9rosion lente des communaut\u00e9s autrefois pleines de promesses. Ses visuels \u00e9pur\u00e9s, ses hymnes de bluegrass hant\u00e9s et ses perspectives narratives changeantes en font non seulement un jeu ind\u00e9pendant remarquable, mais aussi l&rsquo;une des \u0153uvres gothiques du Sud les plus \u00e9vocatrices et essentielles du domaine du jeu vid\u00e9o.<\/p>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"5-red-dead-redemption-2-2018\"><strong>5. Red Dead Redemption 2 (2018)<\/strong><\/h3>\n<p><em>Plateforme : PC, PlayStation, Xbox<\/em><\/p>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/red-dead-redemption-2-1.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/red-dead-redemption-2-1.jpg\" alt=\"Une capture d'\u00e9cran de Red Dead Redemption 2\" class=\"wp-image-169882\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/red-dead-redemption-2-1.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/red-dead-redemption-2-1-768x432.jpg 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/red-dead-redemption-2-1-150x84.jpg 150w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/red-dead-redemption-2-1-300x169.jpg 300w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/red-dead-redemption-2-1-696x392.jpg 696w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/red-dead-redemption-2-1-1068x601.jpg 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">Rockstar Games<\/figcaption><\/figure>\n<p><\/a><\/div>\n<p><em><a href=\"https:\/\/store.steampowered.com\/app\/1174180\/Red_Dead_Redemption_2\/\" target=\"_blank\" rel=\"noopener\">Red Dead Redemption 2<\/a><\/em> est un vaste western atmosph\u00e9rique qui fait \u00e9galement partie des exp\u00e9riences gothiques du Sud les plus marquantes dans le domaine du jeu vid\u00e9o. Situ\u00e9 dans une fronti\u00e8re am\u00e9ricaine mourante \u00e0 la fin du XIXe si\u00e8cle, le jeu suit Arthur Morgan, un hors-la-loi fatigu\u00e9 d\u00e9chir\u00e9 entre sa loyaut\u00e9 envers sa bande en d\u00e9composition et sa propre boussole morale en d\u00e9clin. Le gameplay se d\u00e9roule dans un monde ouvert magnifiquement rendu, rempli d&rsquo;histoires \u00e9mergentes, de d\u00e9cisions moralement ambigu\u00ebs, et de vignettes hant\u00e9es de d\u00e9composition, de d\u00e9sespoir et de beaut\u00e9.<\/p>\n<\/div>\n<\/div>\n<p>Ce n&rsquo;est pas seulement des fusillades et des braquages\u2014les joueurs chassent, p\u00eachent, jouent aux cartes, s&rsquo;occupent de leur cheval ou s&rsquo;assoient pr\u00e8s du feu \u00e0 \u00e9couter des histoires de fant\u00f4mes et des confessions personnelles. Les th\u00e8mes de pourriture, d&rsquo;id\u00e9aux perdus, de structures sociales en d\u00e9composition et de r\u00e9flexion existentielle sont purement gothiques du Sud, racont\u00e9s \u00e0 travers des porches qui craquent, des mar\u00e9cages embrum\u00e9s, et la douleur des r\u00eaves qui s&rsquo;estompent. Peu de jeux capturent la po\u00e9sie tragique du Sud comme celui-ci.<\/p>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"4-scarlet-hollow-2021-ongoing\"><strong>4. Scarlet Hollow (2021 &#8211; En cours)<\/strong><\/h3>\n<p><em>Plateforme : PC<\/em><\/p>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/scarlet-hollow-1.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/scarlet-hollow-1.jpg\" alt=\"Une capture d'\u00e9cran de Scarlet Hollow\" class=\"wp-image-169891\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/scarlet-hollow-1.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/scarlet-hollow-1-768x432.jpg.webp 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/scarlet-hollow-1-150x84.jpg 150w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/scarlet-hollow-1-300x169.jpg.webp 300w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/scarlet-hollow-1-696x392.jpg.webp 696w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/scarlet-hollow-1-1068x601.jpg.webp 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">Black Tabby Games<\/figcaption><\/figure>\n<p><\/a><\/div>\n<p><em><a href=\"https:\/\/store.steampowered.com\/app\/1609230\/Scarlet_Hollow\/\" target=\"_blank\" rel=\"noopener\">Scarlet Hollow<\/a><\/em> est un roman visuel d&rsquo;horreur-myst\u00e8re gothique du Sud qui vous plonge au c\u0153ur d&rsquo;une petite ville appalachienne en d\u00e9composition, remplie de secrets, de chagrin et d&rsquo;angoisse rampante. Il m\u00e9lange une \u00e9criture aiguis\u00e9e et \u00e9motionnellement r\u00e9sonnante avec un art \u00e0 l&rsquo;encre dessin\u00e9 \u00e0 la main pour cr\u00e9er un r\u00e9cit ramifi\u00e9 et ax\u00e9 sur le choix o\u00f9 chaque d\u00e9cision compte\u2014jusqu&rsquo;\u00e0 votre capacit\u00e9 \u00e0 parler aux animaux ou \u00e0 s\u00e9duire un monstre. \u00c0 travers sa structure \u00e9pisoidique (quatre des sept chapitres actuellement sortis), vous d\u00e9m\u00ealez un myst\u00e8re surnaturel \u00e0 combustion lente tout en naviguant dans des relations compliqu\u00e9es, un traumatisme g\u00e9n\u00e9rationnel, et le silence troublant de la d\u00e9composition rurale.<\/p>\n<\/div>\n<\/div>\n<p>C&rsquo;est gothique du Sud jusqu&rsquo;\u00e0 l&rsquo;os : des parents d\u00e9c\u00e9d\u00e9s, des lign\u00e9es maudites, des mines hant\u00e9es, et des personnages si richement \u00e9crits que vous aurez l&rsquo;impression de les avoir d\u00e9j\u00e0 rencontr\u00e9s, ou peut-\u00eatre r\u00eav\u00e9s. Ce n&rsquo;est pas juste une histoire de monstres ; c&rsquo;est sur la pourriture sous la surface de la famille et de la communaut\u00e9\u2014ce qui en fait une entr\u00e9e essentielle dans notre liste de jeux gothiques du Sud.<\/p>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"3-resident-evil-7-biohazard-2017\"><strong>3. Resident Evil 7: Biohazard (2017)<\/strong><\/h3>\n<p><em>Plateforme : PC, PlayStation, Xbox<\/em><\/p>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/resident-evil-7-biohazard-1.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/resident-evil-7-biohazard-1.jpg\" alt=\"Une capture d'\u00e9cran de Resident Evil 7: Biohazard\" class=\"wp-image-169909\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/resident-evil-7-biohazard-1.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/resident-evil-7-biohazard-1-768x432.jpg.webp 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/resident-evil-7-biohazard-1-150x84.jpg 150w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/resident-evil-7-biohazard-1-300x169.jpg 300w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/resident-evil-7-biohazard-1-696x392.jpg.webp 696w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/resident-evil-7-biohazard-1-1068x601.jpg.webp 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">CAPCOM Co., Ltd.<\/figcaption><\/figure>\n<p><\/a><\/div>\n<p><em><a href=\"https:\/\/store.steampowered.com\/app\/418370\/Resident_Evil_7_Biohazard\/\" target=\"_blank\" rel=\"noopener\">Resident Evil 7: Biohazard<\/a><\/em> d\u00e9pouille la franchise de ses os tordus et en d\u00e9composition et la reconstruit en un cauchemar gothique du Sud terrifiant \u00e0 la premi\u00e8re personne. Situ\u00e9 au c\u0153ur des mar\u00e9cages ruraux de la Louisiane, vous incarnez Ethan Winters, un homme \u00e0 la recherche de sa femme disparue dans une maison de plantation en ruine, hant\u00e9e non par des fant\u00f4mes, mais par la grotesque et d\u00e9rang\u00e9e famille Baker. Le passage \u00e0 la premi\u00e8re personne rend chaque plancher qui craque et chaque couloir tach\u00e9 de sang \u00e9touffant de proximit\u00e9, tandis que des ressources limit\u00e9es, un design de niveau labyrinthique, et une horreur corporelle grotesque canalisent les racines de l&rsquo;horreur de survie de la franchise.<\/p>\n<\/div>\n<\/div>\n<p>Ce qui fait de <em>RE7<\/em> un jeu gothique du Sud par excellence n&rsquo;est pas seulement le cadre\u2014c&rsquo;est l&rsquo;h\u00e9ritage familial en d\u00e9composition, le sentiment d&rsquo;isolement, et la fusion \u00e9trange d&rsquo;hospitalit\u00e9 et d&rsquo;horreur. C&rsquo;est Flannery O&rsquo;Connor rencontre <em>The Texas Chain Saw Massacre<\/em>, imbib\u00e9 de moisissure et de clair de lune.<\/p>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"2-norco-2022\"><strong>2. Norco (2022)<\/strong><\/h3>\n<p><em>Plateforme : PC, PlayStation, Xbox<\/em><\/p>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/norco-1.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/norco-1.jpg\" alt=\"Une capture d'\u00e9cran de Norco\" class=\"wp-image-169918\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/norco-1.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/norco-1-768x432.jpg 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/norco-1-150x84.jpg 150w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/norco-1-300x169.jpg 300w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/norco-1-696x392.jpg.webp 696w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/norco-1-1068x601.jpg 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">Raw Fury<\/figcaption><\/figure>\n<p><\/a><\/div>\n<p><a href=\"https:\/\/store.steampowered.com\/app\/1221250\/NORCO\/\" target=\"_blank\" rel=\"noopener\"><em>NORCO<\/em> <\/a>est une aventure point-and-click surr\u00e9aliste et ax\u00e9e sur le dialogue, se d\u00e9roulant dans une version industrielle en d\u00e9composition du Sud de la Louisiane qui se sent \u00e0 la fois \u00e9trangement futuriste et trop famili\u00e8re. M\u00e9langeant des \u00e9l\u00e9ments gothiques du Sud et de la fiction sp\u00e9culative, le jeu suit Kay alors qu&rsquo;elle rentre chez elle apr\u00e8s la mort de sa m\u00e8re, seulement pour d\u00e9couvrir que son fr\u00e8re est port\u00e9 disparu et que sa ville natale a \u00e9t\u00e9 transform\u00e9e par l&#8217;empi\u00e8tement des entreprises et la pourriture spirituelle. Le gameplay se concentre sur l&rsquo;exploration, la r\u00e9solution d&rsquo;\u00e9nigmes, et des conversations richement \u00e9crites, livr\u00e9es \u00e0 travers des pixel arts hant\u00e9s et une bande sonore atmosph\u00e9rique qui ressemble \u00e0 un r\u00eave humide charg\u00e9 de signification.<\/p>\n<\/div>\n<\/div>\n<p>Ce qui fait que <em>NORCO<\/em> se distingue\u2014et m\u00e9rite sa place sur n&rsquo;importe quelle liste de jeux gothiques du Sud\u2014c&rsquo;est sa voix r\u00e9gionaliste sans excuses, ses th\u00e8mes profond\u00e9ment personnels de chagrin, de m\u00e9moire, et de d\u00e9composition environnementale, et sa capacit\u00e9 \u00e0 transformer un lieu r\u00e9el en quelque chose de mythique et d&rsquo;\u00e9trange sans perdre son ancrage \u00e9motionnel. Ce n&rsquo;est pas juste un jeu sur le Sud\u2014c&rsquo;est le Sud, brut, \u00e9trange, et inoubliable.<\/p>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"1-south-of-midnight-2025\"><strong>1. South of Midnight (2025)<\/strong><\/h3>\n<p><em>Plateforme : Xbox Series X\/S, PC (Game Pass)<\/em><\/p>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/south-of-midnight-2.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/south-of-midnight-2.jpg\" alt=\"Une capture d'\u00e9cran de South of Midnight\" class=\"wp-image-169927\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/south-of-midnight-2.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/south-of-midnight-2-768x432.jpg.webp 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/south-of-midnight-2-150x84.jpg 150w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/04\/south-of-midnight-2-300x169.jpg 300w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/south-of-midnight-2-696x392.jpg.webp 696w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/04\/south-of-midnight-2-1068x601.jpg.webp 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">Xbox Game Studios<\/figcaption><\/figure>\n<p><\/a><\/div>\n<p><em><a href=\"https:\/\/store.steampowered.com\/app\/1934570\/South_of_Midnight\/\" target=\"_blank\" rel=\"noopener\">South of Midnight<\/a><\/em> est un jeu d&rsquo;action-aventure \u00e0 la troisi\u00e8me personne au style hant\u00e9 qui tisse ensemble le folklore gothique du Sud, une narration \u00e9motionnelle, et une esth\u00e9tique visuelle picturale. Vous incarnez Hazel, une jeune femme propuls\u00e9e dans une version mystique du Sud profond apr\u00e8s un ouragan, o\u00f9 elle prend le manteau d&rsquo;un \u00ab Tisseuse \u00bb\u2014une restauratrice magique des esprits bris\u00e9s et de l&rsquo;histoire familiale. Le jeu suit une structure largement lin\u00e9aire avec des plateformes, des vignettes narratives, et des ar\u00e8nes de combat entrecoup\u00e9es de rencontres impr\u00e9gn\u00e9es de folklore.<\/p>\n<\/div>\n<\/div>\n<p>Bien que le gameplay s&rsquo;appuie sur des m\u00e9caniques famili\u00e8res et la r\u00e9p\u00e9tition, c&rsquo;est l&rsquo;atmosph\u00e8re riche, profond\u00e9ment ancr\u00e9e dans les traditions spirituelles afro-am\u00e9ricaines, et la bande sonore inoubliable d&rsquo;Olivier Deriviere qui \u00e9l\u00e8vent vraiment l&rsquo;exp\u00e9rience. Avec son cadre \u00e9vocateur, ses personnages \u00e9mouvants, et son exploration du traumatisme g\u00e9n\u00e9rationnel \u00e0 travers le mythe, <em>South of Midnight<\/em> m\u00e9rite sa place parmi les meilleurs jeux gothiques du Sud pour la mani\u00e8re dont il capture pleinement la magie m\u00e9lancolique de la r\u00e9gion.<\/p>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"closing-the-screen-door-gently\"><strong>Fermer doucement la porte moustiquaire\u2026<\/strong><\/h3>\n<p>Les jeux gothiques du Sud ne parlent pas de r\u00e9flexes rapides ou de fantasmes de puissance\u2014ils concernent l&rsquo;atmosph\u00e8re, l&rsquo;h\u00e9ritage et l&rsquo;angoisse qui persiste comme un nuage d&rsquo;orage sur le porche. Que vous soyez en train de d\u00e9m\u00ealer des conspirations dans <em>NORCO<\/em>, de fuir un traumatisme g\u00e9n\u00e9rationnel dans <em>Resident Evil 7<\/em>, ou de vagabonder sur des routes hant\u00e9es dans <em>Kentucky Route Zero<\/em>, chacun de ces jeux vous permet de go\u00fbter au Sud tel qu&rsquo;il se ressent apr\u00e8s minuit : \u00e9pais, tremblant, et plein de fant\u00f4mes.<\/p>\n<p>Alors, servez-vous un peu de th\u00e9 glac\u00e9\u2014avec ou sans alcool\u2014et plongez dans ces mondes \u00e9tranges. Juste faites attention \u00e0 l&rsquo;endroit o\u00f9 vous creusez. Vous pourriez ne pas aimer ce que vous trouvez.<\/p>\n<\/div>\n<\/div>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<h3 class=\"wp-block-heading\" id=\"faq-best-southern-gothic-games\"><strong>FAQ : Meilleurs jeux gothiques du Sud<\/strong><\/h3>\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1744954612112\" class=\"rank-math-list-item\">\n<h5 class=\"rank-math-question \"><strong>Qu&rsquo;est-ce qui rend un jeu gothique du Sud ?<\/strong><\/h5>\n<div class=\"rank-math-answer \">\n<p>Les jeux gothiques du Sud m\u00e9langent des \u00e9l\u00e9ments surnaturels ou macabres avec des th\u00e8mes du monde r\u00e9el comme l&rsquo;h\u00e9ritage familial, la d\u00e9cadence sociale, et la beaut\u00e9 inqui\u00e9tante du Sud am\u00e9ricain. Attendez-vous \u00e0 des maisons hant\u00e9es, des paysages mar\u00e9cageux, un traumatisme g\u00e9n\u00e9rationnel, et une forte emphase sur l&rsquo;ambiance et la narration.<\/p>\n<\/div>\n<\/div>\n<div id=\"faq-question-1744954639062\" class=\"rank-math-list-item\">\n<h5 class=\"rank-math-question \"><strong>Est-ce que <em>South of Midnight<\/em> vaut le coup d&rsquo;\u00eatre jou\u00e9 ?<\/strong><\/h5>\n<div class=\"rank-math-answer \">\n<p>Oui, <em>South of Midnight<\/em> (2025) est une entr\u00e9e remarquable dans le genre gr\u00e2ce \u00e0 sa profondeur folklorique, sa direction artistique unique, et son histoire \u00e9motionnellement r\u00e9sonnante. Bien que son combat puisse \u00eatre un peu r\u00e9p\u00e9titif, l&rsquo;atmosph\u00e8re, la musique, et les personnages en font un must pour les fans d&rsquo;exp\u00e9riences narratives.<\/p>\n<\/div>\n<\/div>\n<div id=\"faq-question-1744954646032\" class=\"rank-math-list-item\">\n<h5 class=\"rank-math-question \"><strong>Y a-t-il des jeux gothiques du Sud avec peu de combat ?<\/strong><\/h5>\n<div class=\"rank-math-answer \">\n<p>Absolument\u2014<em>Kentucky Route Zero<\/em> et <em>Scarlet Hollow<\/em> se concentrent fortement sur la narration et la r\u00e9sonance \u00e9motionnelle, avec peu ou pas de combat traditionnel. Ce sont d&rsquo;excellents choix si vous \u00eates plus int\u00e9ress\u00e9 par l&rsquo;atmosph\u00e8re et les personnages que par l&rsquo;action.<\/p>\n<\/div>\n<\/div>\n<div id=\"faq-question-1744954657695\" class=\"rank-math-list-item\">\n<h5 class=\"rank-math-question \"><strong>Quel jeu gothique du Sud a les \u00e9l\u00e9ments d&rsquo;horreur les plus forts ?<\/strong><\/h5>\n<div class=\"rank-math-answer \">\n<p><em>Resident Evil 7: Biohazard<\/em> s&rsquo;engage fermement dans l&rsquo;horreur tout en livrant une exp\u00e9rience profond\u00e9ment gothique du Sud. La maison de plantation d\u00e9labr\u00e9e, les dynamiques familiales tordues, et le cadre mar\u00e9cageux en font l&rsquo;une des entr\u00e9es les plus gla\u00e7antes du genre.<\/p>\n<\/div>\n<\/div>\n<div id=\"faq-question-1744954663227\" class=\"rank-math-list-item\">\n<h5 class=\"rank-math-question \"><strong>Puis-je jouer \u00e0 ces jeux sur des consoles modernes ?<\/strong><\/h5>\n<div class=\"rank-math-answer \">\n<p>La plupart des meilleurs jeux gothiques du Sud\u2014comme <em>Red Dead Redemption 2<\/em>, <em>Mafia III<\/em>, <em>South of Midnight<\/em>, et <em>Alone in the Dark (2024)<\/em>\u2014sont disponibles sur PlayStation 5, Xbox Series X\/S, ou PC. Des jeux ind\u00e9pendants comme <em>NORCO<\/em> et <em>Scarlet Hollow<\/em> sont \u00e9galement accessibles sur plusieurs plateformes.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous cherchez les meilleurs jeux gothiques du Sud qui m\u00e9langent terreur, d\u00e9composition et beaut\u00e9 sombre ? De South of Midnight \u00e0 Resident Evil 7, cette liste class\u00e9e d&rsquo;aventures atmosph\u00e9riques explore des plantations hant\u00e9es, un folklore mystique et les \u00e9chos inqui\u00e9tants du pass\u00e9 ombrag\u00e9 de l&rsquo;Am\u00e9rique.<\/p>\n","protected":false},"author":83,"featured_media":169936,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[746],"tags":[],"class_list":{"0":"post-169949","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-non-classifiee"},"wpml_current_locale":"fr_FR","wpml_translations":{"en_US":{"locale":"en_US","id":169836,"slug":"best-southern-gothic-games-2025","post_title":"The Best Southern Gothic Games to Play in 2025: Swamps, Secrets, and Spirits","href":"https:\/\/outsidergaming.com\/best-southern-gothic-games-2025\/"},"de_DE":{"locale":"de_DE","id":169948,"slug":"die-besten-southern-gothic-spiele-die-man-2025-spielen-sollte-sumpfe-geheimnisse-und-geister","post_title":"Die besten Southern Gothic Spiele, die man 2025 spielen sollte: S\u00fcmpfe, Geheimnisse und Geister","href":"https:\/\/outsidergaming.com\/de\/die-besten-southern-gothic-spiele-die-man-2025-spielen-sollte-sumpfe-geheimnisse-und-geister\/"},"fr_FR":{"locale":"fr_FR","translation":"current"},"es_ES":{"locale":"es_ES","id":169946,"slug":"los-mejores-juegos-del-sur-gotico-para-jugar-en-2025-pantanos-secretos-y-espiritus","post_title":"Los mejores juegos del sur g\u00f3tico para jugar en 2025: pantanos, secretos y esp\u00edritus","href":"https:\/\/outsidergaming.com\/es\/los-mejores-juegos-del-sur-gotico-para-jugar-en-2025-pantanos-secretos-y-espiritus\/"},"ru_RU":{"locale":"ru_RU","id":169947,"slug":"%d0%bb%d1%83%d1%87%d1%88%d0%b8%d0%b5-%d1%8e%d0%b6%d0%bd%d1%8b%d0%b5-%d0%b3%d0%be%d1%82%d0%b8%d1%87%d0%b5%d1%81%d0%ba%d0%b8%d0%b5-%d0%b8%d0%b3%d1%80%d1%8b-%d0%b4%d0%bb%d1%8f-%d0%b8%d0%b3%d1%80%d1%8b","post_title":"\u041b\u0443\u0447\u0448\u0438\u0435 \u044e\u0436\u043d\u044b\u0435 \u0433\u043e\u0442\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u0438\u0433\u0440\u044b \u0434\u043b\u044f \u0438\u0433\u0440\u044b \u0432 2025 \u0433\u043e\u0434\u0443: \u0411\u043e\u043b\u043e\u0442\u0430, \u0422\u0430\u0439\u043d\u044b \u0438 \u0414\u0443\u0445\u0438","href":"https:\/\/outsidergaming.com\/ru\/%d0%bb%d1%83%d1%87%d1%88%d0%b8%d0%b5-%d1%8e%d0%b6%d0%bd%d1%8b%d0%b5-%d0%b3%d0%be%d1%82%d0%b8%d1%87%d0%b5%d1%81%d0%ba%d0%b8%d0%b5-%d0%b8%d0%b3%d1%80%d1%8b-%d0%b4%d0%bb%d1%8f-%d0%b8%d0%b3%d1%80%d1%8b\/"},"pt_BR":{"locale":"pt_BR","id":169950,"slug":"os-melhores-jogos-goticos-do-sul-para-jogar-em-2025-pantanos-segredos-e-espiritos","post_title":"Os Melhores Jogos G\u00f3ticos do Sul para Jogar em 2025: P\u00e2ntanos, Segredos e Esp\u00edritos","href":"https:\/\/outsidergaming.com\/pt-br\/os-melhores-jogos-goticos-do-sul-para-jogar-em-2025-pantanos-segredos-e-espiritos\/"},"it_IT":{"locale":"it_IT","id":169953,"slug":"i-migliori-giochi-gotici-del-sud-da-giocare-nel-2025-paludi-segreti-e-spiriti","post_title":"I migliori giochi gotici del sud da giocare nel 2025: paludi, segreti e spiriti","href":"https:\/\/outsidergaming.com\/it\/i-migliori-giochi-gotici-del-sud-da-giocare-nel-2025-paludi-segreti-e-spiriti\/"},"tr_TR":{"locale":"tr_TR","id":169951,"slug":"2025te-oynanacak-en-iyi-guney-gotik-oyunlar-batakliklar-sirlar-ve-ruhlar","post_title":"2025'te Oynanacak En \u0130yi G\u00fcney Gotik Oyunlar: Batakl\u0131klar, S\u0131rlar ve Ruhlar","href":"https:\/\/outsidergaming.com\/tr\/2025te-oynanacak-en-iyi-guney-gotik-oyunlar-batakliklar-sirlar-ve-ruhlar\/"},"ukr":{"locale":"ukr","id":169954,"slug":"%d0%bd%d0%b0%d0%b9%d0%ba%d1%80%d0%b0%d1%89%d1%96-%d0%bf%d1%96%d0%b2%d0%b4%d0%b5%d0%bd%d0%bd%d1%96-%d0%b3%d0%be%d1%82%d0%b8%d1%87%d0%bd%d1%96-%d1%96%d0%b3%d1%80%d0%b8-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80","post_title":"\u041d\u0430\u0439\u043a\u0440\u0430\u0449\u0456 \u043f\u0456\u0432\u0434\u0435\u043d\u043d\u0456 \u0433\u043e\u0442\u0438\u0447\u043d\u0456 \u0456\u0433\u0440\u0438 \u0434\u043b\u044f \u0433\u0440\u0438 \u0443 2025 \u0440\u043e\u0446\u0456: \u0411\u043e\u043b\u043e\u0442\u0430, \u0421\u0435\u043a\u0440\u0435\u0442\u0438 \u0442\u0430 \u0414\u0443\u0445\u0438","href":"https:\/\/outsidergaming.com\/uk\/%d0%bd%d0%b0%d0%b9%d0%ba%d1%80%d0%b0%d1%89%d1%96-%d0%bf%d1%96%d0%b2%d0%b4%d0%b5%d0%bd%d0%bd%d1%96-%d0%b3%d0%be%d1%82%d0%b8%d1%87%d0%bd%d1%96-%d1%96%d0%b3%d1%80%d0%b8-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80\/"}},"_links":{"self":[{"href":"https:\/\/outsidergaming.com\/fr\/wp-json\/wp\/v2\/posts\/169949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/outsidergaming.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/outsidergaming.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/outsidergaming.com\/fr\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/outsidergaming.com\/fr\/wp-json\/wp\/v2\/comments?post=169949"}],"version-history":[{"count":0,"href":"https:\/\/outsidergaming.com\/fr\/wp-json\/wp\/v2\/posts\/169949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/outsidergaming.com\/fr\/wp-json\/wp\/v2\/media\/169936"}],"wp:attachment":[{"href":"https:\/\/outsidergaming.com\/fr\/wp-json\/wp\/v2\/media?parent=169949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/outsidergaming.com\/fr\/wp-json\/wp\/v2\/categories?post=169949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/outsidergaming.com\/fr\/wp-json\/wp\/v2\/tags?post=169949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}