{"id":154822,"date":"2024-12-12T13:35:55","date_gmt":"2024-12-12T12:35:55","guid":{"rendered":"https:\/\/outsidergaming.com\/arma-reforger-esta-finalmente-disponivel-para-jogar-no-ps5\/"},"modified":"2024-12-12T23:25:10","modified_gmt":"2024-12-12T22:25:10","slug":"arma-reforger-esta-finalmente-disponivel-para-jogar-no-ps5","status":"publish","type":"post","link":"https:\/\/outsidergaming.com\/pt-br\/arma-reforger-esta-finalmente-disponivel-para-jogar-no-ps5\/","title":{"rendered":"Arma Reforger Est\u00e1 Finalmente Dispon\u00edvel para Jogar no PS5"},"content":{"rendered":"<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\"><iframe title=\"Arma Reforger - Trailer de Lan\u00e7amento | Jogos PS5\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/vAY9i2RG5Fc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/figure>\n<p>A espera acabou para os jogadores de <a href=\"https:\/\/outsidergaming.com\/playstation\/\">PlayStation<\/a> ansiosos para experimentar uma das franquias de simula\u00e7\u00e3o militar mais aclamadas. A Bohemia Interactive lan\u00e7ou oficialmente <em>Arma Reforger<\/em> no PlayStation 5, trazendo sua jogabilidade realista de sandbox militar para a plataforma de console pela primeira vez. Com a pot\u00eancia do Enfusion Engine, <em>Arma Reforger<\/em> promete um novo n\u00edvel de desempenho, gr\u00e1ficos aprimorados e recursos adaptados especificamente para os jogadores de PS5.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Um Marco para a Franquia Arma<\/strong><\/h3>\n<p>Desde sua cria\u00e7\u00e3o h\u00e1 mais de duas d\u00e9cadas, a s\u00e9rie <em>Arma<\/em> estabeleceu o padr\u00e3o para jogos de simula\u00e7\u00e3o militar, conquistando uma reputa\u00e7\u00e3o de realismo incompar\u00e1vel e jogabilidade em mundo aberto. De <em>Arma: Cold War Assault<\/em> (2001) a <em>Arma 3<\/em> (2013), a franquia sempre superou os limites do que os simuladores militares podem alcan\u00e7ar. Agora, com <em>Arma Reforger<\/em>, a Bohemia Interactive oferece aos jogadores de PlayStation a chance de mergulhar na a\u00e7\u00e3o como nunca antes.<\/p>\n<p>Ambientado em um cen\u00e1rio aut\u00eantico da era da Guerra Fria, <em>Arma Reforger<\/em> apresenta aos jogadores as ilhas fict\u00edcias de Everon e Arland. Com uma \u00e1rea combinada de 61 km\u00b2, essas paisagens expansivas s\u00e3o meticulosamente detalhadas, apresentando armas, ve\u00edculos e equipamentos espec\u00edficos da \u00e9poca que trazem o cen\u00e1rio de 1989 \u00e0 vida.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-82.png\" alt=\"\" class=\"wp-image-154726\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-82.png 1280w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-82-768x432.png 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-82-150x84.png 150w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-82-300x169.png 300w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-82-696x392.png 696w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-82-1068x601.png 1068w\" sizes=\"(max-width: 1280px) 100vw, 1280px\"><\/figure>\n<h3 class=\"wp-block-heading\"><strong>Recursos Exclusivos para PS5<\/strong><\/h3>\n<p><em>Arma Reforger<\/em> foi otimizado para aproveitar ao m\u00e1ximo as capacidades de hardware do PS5, proporcionando uma experi\u00eancia de jogo mais suave e imersiva. Recursos exclusivos para o controle DualSense incluem:<\/p>\n<ul class=\"wp-block-list\">\n<li><strong>Gatilhos Adaptativos<\/strong>: Resist\u00eancia vari\u00e1vel adaptada a cada tipo de arma, aprimorando a sensa\u00e7\u00e3o t\u00e1til de cada tiro disparado.<\/li>\n<li><strong>Feedback H\u00e1ptico<\/strong>: Vibra\u00e7\u00f5es precisas que simulam o ambiente e as a\u00e7\u00f5es, seja o rugido de um ve\u00edculo ou o recuo de uma arma.<\/li>\n<li><strong>Controles de Movimento<\/strong>: Ajuste sua mira e movimentos com entrada de movimento para maior precis\u00e3o.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading\"><strong>Modos de Jogo para Todos os Estilos<\/strong><\/h3>\n<p>Seja voc\u00ea um f\u00e3 de estrat\u00e9gia, coopera\u00e7\u00e3o ou a\u00e7\u00e3o r\u00e1pida, <em>Arma Reforger<\/em> oferece quatro modos de jogo distintos para todos os tipos de jogadores:<\/p>\n<ol class=\"wp-block-list\">\n<li><strong>Conflito<\/strong>: Um modo multiplayer em larga escala onde equipes lutam pelo controle de pontos-chave em duas ilhas massivas. Al\u00e9m do combate, os jogadores devem gerenciar log\u00edstica, construir estruturas e criar estrat\u00e9gias para garantir a vit\u00f3ria.<\/li>\n<li><strong>Mestre do Jogo<\/strong>: Um modo sandbox criativo onde os jogadores podem criar miss\u00f5es e cen\u00e1rios personalizados. Os Mestres do Jogo podem ajustar esses cen\u00e1rios em tempo real, criando experi\u00eancias \u00fanicas e din\u00e2micas.<\/li>\n<li><strong>Opera\u00e7\u00f5es de Combate<\/strong>: Projetado para jogabilidade cooperativa ou solo, este modo desafia os jogadores com objetivos din\u00e2micos e miss\u00f5es t\u00e1ticas intensas.<\/li>\n<li><strong>Captura e Manuten\u00e7\u00e3o<\/strong>: Um modo de alta intensidade que condensa o realismo caracter\u00edstico de <em>Arma<\/em> em partidas curtas e repletas de a\u00e7\u00e3o.<\/li>\n<\/ol>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-81.png\" alt=\"\" class=\"wp-image-154720\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-81.png 1280w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-81-768x432.png 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-81-150x84.png 150w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-81-300x169.png 300w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-81-696x392.png 696w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2024\/12\/image-81-1068x601.png 1068w\" sizes=\"(max-width: 1280px) 100vw, 1280px\"><\/figure>\n<h3 class=\"wp-block-heading\"><strong>Crossplay e Atualiza\u00e7\u00f5es Futuras<\/strong><\/h3>\n<p>Um dos recursos mais empolgantes de <em>Arma Reforger<\/em> \u00e9 o crossplay, permitindo que jogadores de diferentes plataformas se engajem em batalhas juntos sem problemas. Embora a modifica\u00e7\u00e3o\u2014uma marca registrada da s\u00e9rie <em>Arma<\/em>\u2014n\u00e3o esteja dispon\u00edvel na vers\u00e3o para PS5, a Bohemia Interactive confirmou planos para introduzir esse recurso em atualiza\u00e7\u00f5es futuras, garantindo que a comunidade PlayStation possa aproveitar a criatividade do vasto ecossistema de modding de <em>Arma<\/em>.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Pre\u00e7o e Disponibilidade<\/strong><\/h3>\n<p><em>Arma Reforger<\/em> j\u00e1 est\u00e1 dispon\u00edvel por $39,99 USD (\u20ac39,99 EUR \/ \u00a339,99 GBP) <a href=\"https:\/\/store.playstation.com\/en-us\/product\/EP2601-PPSA24605_00-0538909601464686\/\" target=\"_blank\" rel=\"noopener\">na PlayStation Store<\/a>. Mas os compradores devem saber que <strong>uma assinatura do PlayStation Plus \u00e9 necess\u00e1ria para o multiplayer online<\/strong>, que suporta at\u00e9 64 jogadores.<\/p>\n<p>Para mais detalhes e atualiza\u00e7\u00f5es, visite o <a href=\"https:\/\/reforger.armaplatform.com\" target=\"_blank\" rel=\"noopener\">site oficial de Arma Reforger<\/a> ou junte-se \u00e0 conversa no servidor do Discord do Arma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arma Reforger j\u00e1 est\u00e1 dispon\u00edvel no PS5, trazendo a jogabilidade realista de simula\u00e7\u00e3o militar da Bohemia Interactive para os jogadores do PlayStation pela primeira vez, com suporte exclusivo ao controle DualSense, crossplay e combates din\u00e2micos da era da Guerra Fria.<\/p>\n","protected":false},"author":83,"featured_media":154733,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1046,1042,1029],"tags":[],"class_list":{"0":"post-154822","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"category-playstation-pt-br","9":"category-nao-categorizado"},"wpml_current_locale":"pt_BR","wpml_translations":{"en_US":{"locale":"en_US","id":154713,"slug":"arma-reforger-is-finally-available-to-play-on-the-ps5","post_title":"Arma Reforger is Finally Available to Play on the PS5","href":"https:\/\/outsidergaming.com\/arma-reforger-is-finally-available-to-play-on-the-ps5\/"},"de_DE":{"locale":"de_DE","id":154820,"slug":"arma-reforger-ist-endlich-auf-der-ps5-spielbar","post_title":"Arma Reforger ist endlich auf der PS5 spielbar!","href":"https:\/\/outsidergaming.com\/de\/arma-reforger-ist-endlich-auf-der-ps5-spielbar\/"},"fr_FR":{"locale":"fr_FR","id":154821,"slug":"arma-reforger-est-enfin-disponible-sur-ps5","post_title":"Arma Reforger est enfin disponible sur PS5","href":"https:\/\/outsidergaming.com\/fr\/arma-reforger-est-enfin-disponible-sur-ps5\/"},"es_ES":{"locale":"es_ES","id":154819,"slug":"arma-reforger-ya-esta-disponible-para-jugar-en-ps5","post_title":"Arma Reforger ya est\u00e1 disponible para jugar en PS5","href":"https:\/\/outsidergaming.com\/es\/arma-reforger-ya-esta-disponible-para-jugar-en-ps5\/"},"ru_RU":{"locale":"ru_RU","id":154818,"slug":"arma-reforger-%d0%bd%d0%b0%d0%ba%d0%be%d0%bd%d0%b5%d1%86-%d0%b4%d0%be%d1%81%d1%82%d1%83%d0%bf%d0%bd%d0%b0-%d0%b4%d0%bb%d1%8f-%d0%b8%d0%b3%d1%80%d1%8b-%d0%bd%d0%b0-ps5","post_title":"Arma Reforger \u043d\u0430\u043a\u043e\u043d\u0435\u0446 \u0434\u043e\u0441\u0442\u0443\u043f\u043d\u0430 \u0434\u043b\u044f \u0438\u0433\u0440\u044b \u043d\u0430 PS5","href":"https:\/\/outsidergaming.com\/ru\/arma-reforger-%d0%bd%d0%b0%d0%ba%d0%be%d0%bd%d0%b5%d1%86-%d0%b4%d0%be%d1%81%d1%82%d1%83%d0%bf%d0%bd%d0%b0-%d0%b4%d0%bb%d1%8f-%d0%b8%d0%b3%d1%80%d1%8b-%d0%bd%d0%b0-ps5\/"},"pt_BR":{"locale":"pt_BR","translation":"current"},"it_IT":{"locale":"it_IT","translation":false},"tr_TR":{"locale":"tr_TR","translation":false},"ukr":{"locale":"ukr","translation":false}},"_links":{"self":[{"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/posts\/154822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/comments?post=154822"}],"version-history":[{"count":0,"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/posts\/154822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/media\/154733"}],"wp:attachment":[{"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/media?parent=154822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/categories?post=154822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/tags?post=154822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}