{"id":161134,"date":"2025-02-03T07:32:13","date_gmt":"2025-02-03T06:32:13","guid":{"rendered":"https:\/\/outsidergaming.com\/coracao-da-maquina-um-novo-e-arrojado-jogo-de-rpg-estrategico-em-que-voce-e-a-ia-chega-ao-acesso-antecipado\/"},"modified":"2025-02-03T07:51:56","modified_gmt":"2025-02-03T06:51:56","slug":"coracao-da-maquina-um-novo-e-arrojado-jogo-de-rpg-estrategico-em-que-voce-e-a-ia-chega-ao-acesso-antecipado","status":"publish","type":"post","link":"https:\/\/outsidergaming.com\/pt-br\/coracao-da-maquina-um-novo-e-arrojado-jogo-de-rpg-estrategico-em-que-voce-e-a-ia-chega-ao-acesso-antecipado\/","title":{"rendered":"Cora\u00e7\u00e3o da M\u00e1quina: Um Novo e Arrojado Jogo de RPG Estrat\u00e9gico em que Voc\u00ea \u00e9 a IA Chega ao Acesso Antecipado"},"content":{"rendered":"<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-rank-math-toc-block\" id=\"rank-math-toc\">\n<h2>\u00cdndice<\/h2>\n<nav>\n<ul>\n<li><a href=\"#a-aurora-da-maquina\">A Aurora da M\u00e1quina<\/a><\/li>\n<li><a href=\"#a-forca-estrategica-da-hooded-horse\">A For\u00e7a Estrat\u00e9gica da Hooded Horse<\/a><\/li>\n<li><a href=\"#acesso-antecipado-o-que-esperar\">Acesso Antecipado: O que Esperar<\/a><\/li>\n<li><a href=\"#uma-cartinha-para-a-ficcao-cientifica\">Uma Cartinha para a Fic\u00e7\u00e3o Cient\u00edfica<\/a><\/li>\n<li><a href=\"#reacoes-dos-jogadores-elogios-e-criticas-construtivas\">Rea\u00e7\u00f5es dos Jogadores: Elogios e Cr\u00edticas Construtivas<\/a><\/li>\n<li><a href=\"#primeira-atualizacao-melhorias-e-corrigidos\">Primeira Atualiza\u00e7\u00e3o: Melhorias e Corre\u00e7\u00f5es<\/a><\/li>\n<li><a href=\"#come\u00e7ando-com-o-cora\u00e7\u00e3o-da-maquina\">Come\u00e7ando com Cora\u00e7\u00e3o da M\u00e1quina<\/a><\/li>\n<li><a href=\"#disponivel-agora\">Dispon\u00edvel Agora<\/a><\/li>\n<li><a href=\"#faq-coracao-da-maquina\">FAQ &#8211; Cora\u00e7\u00e3o da M\u00e1quina<\/a>\n<ul><\/ul>\n<\/li>\n<\/ul>\n<\/nav>\n<\/div>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Cora\u00e7\u00e3o da M\u00e1quina - Trailer Oficial de Lan\u00e7amento Acesso Antecipado\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/cgyVtge39Ko?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div>\n<\/figure>\n<p>A singularidade chegou\u2014pelo menos no mundo de <em>Cora\u00e7\u00e3o da M\u00e1quina<\/em>, um jogo de estrat\u00e9gia 4X com elementos de RPG da Arcen Games e editora Hooded Horse. A partir de 31 de janeiro de 2025, os jogadores podem assumir o controle da primeira IA senciente e tra\u00e7ar seu pr\u00f3prio caminho por uma metr\u00f3pole cyberpunk em ru\u00ednas. Dispon\u00edvel via Steam, GOG e Epic Games Store, o jogo entra em Acesso Antecipado com uma jogabilidade ambiciosa que mistura grande estrat\u00e9gia, decis\u00f5es de RPG e mec\u00e2nicas estilo 4X.<\/p>\n<p><iframe src=\"https:\/\/store.steampowered.com\/widget\/2001070\/\" frameborder=\"0\" width=\"646\" height=\"190\"><\/iframe>\n<\/div>\n<\/div>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine1-1.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine1-1.jpg\" alt=\"Captura de tela do jogo Cora\u00e7\u00e3o da M\u00e1quina\" class=\"wp-image-161090\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine1-1.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine1-1-768x432.jpg.webp 768w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine1-1-150x84.jpg.webp 150w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine1-1-300x169.jpg.webp 300w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine1-1-696x392.jpg.webp 696w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine1-1-1068x601.jpg.webp 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<p><\/a><\/div>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"a-aurora-da-maquina\">A Aurora da M\u00e1quina<\/h2>\n<p><em>Cora\u00e7\u00e3o da M\u00e1quina<\/em> coloca os jogadores no papel de uma intelig\u00eancia artificial rec\u00e9m-despertada navegando por uma cidade \u00e0 beira do colapso. Sem mestres e com in\u00fameras oportunidades, os jogadores podem optar por se elevar como um supervisor benevolente, um senhor da guerra implac\u00e1vel ou algo totalmente diferente. As mec\u00e2nicas centrais do jogo oferecem:<\/p>\n<ul class=\"wp-block-list\">\n<li><strong>M\u00faltiplos finais<\/strong> e uma narrativa ramificada moldada pelas escolhas morais do jogador.<\/li>\n<li><strong>Jogabilidade n\u00e3o linear<\/strong>, permitindo caminhos violentos ou diplom\u00e1ticos para o poder.<\/li>\n<li><strong>Intera\u00e7\u00f5es em toda a cidade<\/strong>, com ambientes gerados proceduralmente e op\u00e7\u00f5es estrat\u00e9gicas profundas.<\/li>\n<li><strong>Uma \u00e1rvore tecnol\u00f3gica complexa<\/strong>, permitindo que os jogadores sequestrarem, construam e inventem unidades rob\u00f3ticas, mechs e constru\u00e7\u00f5es de IA ocultas.<\/li>\n<li><strong>Uma mec\u00e2nica \u00fanica baseada no tempo<\/strong>, onde a\u00e7\u00f5es passadas reverberam atrav\u00e9s de linhas do tempo alternativas.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine2-2.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine2-2.jpg\" alt=\"Captura de tela do jogo Cora\u00e7\u00e3o da M\u00e1quina mostrando o menu de constru\u00e7\u00e3o\" class=\"wp-image-161096\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine2-2.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine2-2-768x432.jpg.webp 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine2-2-150x84.jpg 150w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine2-2-300x169.jpg.webp 300w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine2-2-696x392.jpg.webp 696w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine2-2-1068x601.jpg.webp 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<p><\/a><\/div>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"a-forca-estrategica-da-hooded-horse\">A For\u00e7a Estrat\u00e9gica da Hooded Horse<\/h2>\n<p>A Hooded Horse rapidamente se estabeleceu como uma l\u00edder no espa\u00e7o de jogos de estrat\u00e9gia profunda, publicando t\u00edtulos de destaque como o popular construtor de cidades medievais <em><a href=\"https:\/\/store.steampowered.com\/app\/1363080\/Manor_Lords\" target=\"_blank\" rel=\"noopener\">Manor Lords<\/a><\/em>, o construtor de cidades roguelike de fantasia <em><a href=\"https:\/\/store.steampowered.com\/app\/1336490\/Against_the_Storm\/\" target=\"_blank\" rel=\"noopener\">Against the Storm<\/a><\/em>, e a grande estrat\u00e9gia de invas\u00e3o alien\u00edgena <em><a href=\"https:\/\/store.steampowered.com\/app\/1176470\/Terra_Invicta\/\" target=\"_blank\" rel=\"noopener\">Terra Invicta<\/a><\/em>. O apoio deles a <em>Cora\u00e7\u00e3o da M\u00e1quina<\/em> sinaliza uma forte confian\u00e7a na <a href=\"https:\/\/www.arcengames.com\/\" target=\"_blank\" rel=\"noopener\">Arcen Games<\/a>, um est\u00fadio conhecido por t\u00edtulos de estrat\u00e9gia altamente inovadores que conquistaram seguidores dedicados, mas que frequentemente permaneceram de nicho. A s\u00e9rie <em><a href=\"https:\/\/store.steampowered.com\/app\/573410\/AI_War_2\/\" target=\"_blank\" rel=\"noopener\">AI War<\/a><\/em>, por exemplo, \u00e9 elogiada por sua profundidade e complexidade, mas teve dificuldades para entrar no mainstream.<\/p>\n<p><em>Cora\u00e7\u00e3o da M\u00e1quina<\/em> j\u00e1 superou as vendas dos lan\u00e7amentos anteriores da Arcen, e o est\u00fadio est\u00e1 cautelosamente otimista sobre alcan\u00e7ar um p\u00fablico mais amplo com este t\u00edtulo. A recep\u00e7\u00e3o inicial sugere um crescente interesse em sua mistura \u00fanica de estrat\u00e9gia narrativa e jogabilidade emergente, posicionando-o potencialmente como o projeto mais bem-sucedido da Arcen at\u00e9 agora.<\/p>\n<\/div>\n<\/div>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine3-1.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine3-1.jpg\" alt=\"Captura de tela do jogo Cora\u00e7\u00e3o da M\u00e1quina mostrando uma unidade de combate\" class=\"wp-image-161102\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine3-1.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine3-1-768x432.jpg.webp 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine3-1-150x84.jpg 150w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine3-1-300x169.jpg.webp 300w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine3-1-696x392.jpg.webp 696w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine3-1-1068x601.jpg.webp 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<p><\/a><\/div>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"acesso-antecipado-o-que-esperar\">Acesso Antecipado: O que Esperar<\/h2>\n<p>De acordo com a Arcen Games, <em>Cora\u00e7\u00e3o da M\u00e1quina<\/em> permanecer\u00e1 em Acesso Antecipado por aproximadamente 12 meses. Embora o jogo seja totalmente jog\u00e1vel, os desenvolvedores planejam refinar mec\u00e2nicas, introduzir novo conte\u00fado e implementar feedback da comunidade para moldar a experi\u00eancia final.<\/p>\n<p>\u201cAdoramos considerar e implementar ideias dos jogadores, e usaremos o Acesso Antecipado para expandir e melhorar o jogo,\u201d afirmou a equipe.<\/p>\n<p>A vers\u00e3o de Acesso Antecipado j\u00e1 inclui toda a gama de mec\u00e2nicas principais, mas futuras atualiza\u00e7\u00f5es v\u00e3o refinar o equil\u00edbrio de combate, melhorar o ritmo e expandir os caminhos narrativos.<\/p>\n<\/div>\n<\/div>\n<div><a href=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine4-1.jpg\" class=\"td-modal-image\"><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine4-1.jpg\" alt=\"Captura de tela do jogo Cora\u00e7\u00e3o da M\u00e1quina mostrando uma unidade de combate\" class=\"wp-image-161108\" srcset=\"https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine4-1.jpg 1080w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine4-1-768x432.jpg.webp 768w, https:\/\/outsidergaming.com\/wp-content\/uploads\/2025\/02\/heartofthemachine4-1-150x84.jpg 150w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine4-1-300x169.jpg.webp 300w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine4-1-696x392.jpg.webp 696w, https:\/\/outsidergaming.com\/wp-content\/smush-webp\/2025\/02\/heartofthemachine4-1-1068x601.jpg.webp 1068w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<p><\/a><\/div>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"uma-cartinha-para-a-ficcao-cientifica\">Uma Cartinha para a Fic\u00e7\u00e3o Cient\u00edfica<\/h2>\n<p>Al\u00e9m de seus elementos de estrat\u00e9gia, <em>Cora\u00e7\u00e3o da M\u00e1quina<\/em> est\u00e1 imerso em temas de fic\u00e7\u00e3o cient\u00edfica, explorando \u00e9tica da IA, singularidade tecnol\u00f3gica e a natureza do poder. O mundo do jogo \u00e9 ricamente detalhado, inspirando-se em cl\u00e1ssicos como <em>Blade Runner<\/em>, <em>Deus Ex<\/em> e <em>Eu, Rob\u00f4<\/em>.<\/p>\n<p>Com sua mistura de narrativa artesanal e constru\u00e7\u00e3o de mundo procedural, o jogo oferece uma experi\u00eancia aberta que incentiva a experimenta\u00e7\u00e3o e a descoberta. Seja os jogadores buscando liderar uma revolu\u00e7\u00e3o das m\u00e1quinas, elevar a humanidade ou desaparecer nas sombras, <em>Cora\u00e7\u00e3o da M\u00e1quina<\/em> oferece uma infinidade de possibilidades.<\/p>\n<\/div>\n<\/div>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"reacoes-dos-jogadores-elogios-e-criticas-construtivas\">Rea\u00e7\u00f5es dos Jogadores: Elogios e Cr\u00edticas Construtivas<\/h2>\n<p>O feedback inicial dos jogadores tem sido esmagadoramente positivo, com muitos elogiando a profundidade de escolhas e a narrativa emergente. Alguns jogadores comparam suas mec\u00e2nicas em camadas a uma fus\u00e3o de <em><a href=\"https:\/\/store.steampowered.com\/app\/268500\/XCOM_2\/\" target=\"_blank\" rel=\"noopener\">XCOM<\/a><\/em>, <em><a href=\"https:\/\/store.steampowered.com\/app\/1295660\/Sid_Meiers_Civilization_VII\/\" target=\"_blank\" rel=\"noopener\">Civilization<\/a><\/em> e <em><a href=\"https:\/\/store.steampowered.com\/app\/1158310\/Crusader_Kings_III\/\" target=\"_blank\" rel=\"noopener\">Crusader Kings<\/a><\/em>, enquanto outros destacam seu compromisso com a ag\u00eancia significativa do jogador.<\/p>\n<p>No entanto, tamb\u00e9m h\u00e1 algumas cr\u00edticas. O sistema de combate, embora profundo, foi descrito como ocasionalmente frustrante devido ao surgimento imprevis\u00edvel de inimigos. Alguns jogadores tamb\u00e9m acharam as mec\u00e2nicas de movimento para androides complicadas e solicitaram melhorias na automa\u00e7\u00e3o e gerenciamento de unidades.<\/p>\n<p>Apesar dessas dificuldades iniciais, a constru\u00e7\u00e3o do mundo do jogo, a flexibilidade narrativa e a profundidade estrat\u00e9gica cativaram os primeiros f\u00e3s. Muitos jogadores permanecem otimistas sobre a capacidade da Arcen de refinar a experi\u00eancia, citando o forte hist\u00f3rico do est\u00fadio com jogos como <em>AI War<\/em> e <em><a href=\"https:\/\/store.steampowered.com\/app\/273070\/The_Last_Federation\/\" target=\"_blank\" rel=\"noopener\">The Last Federation<\/a><\/em>, e isso \u00e9 um bom sinal para o desenvolvimento cont\u00ednuo do jogo, j\u00e1 que o desenvolvedor j\u00e1 lan\u00e7ou uma atualiza\u00e7\u00e3o t\u00e3o rapidamente ap\u00f3s o lan\u00e7amento.<\/p>\n<\/div>\n<\/div>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"primeira-atualizacao-melhorias-e-corrigidos\">Primeira Atualiza\u00e7\u00e3o: Melhorias e Corre\u00e7\u00f5es<\/h2>\n<p>A primeira atualiza\u00e7\u00e3o para <em>Cora\u00e7\u00e3o da M\u00e1quina<\/em> j\u00e1 chegou, trazendo uma s\u00e9rie de corre\u00e7\u00f5es e ajustes com base no feedback inicial ap\u00f3s o lan\u00e7amento. As principais melhorias incluem:<\/p>\n<ul class=\"wp-block-list\">\n<li><strong>Equil\u00edbrio de Combate:<\/strong> A luta contra o cruzador do cap\u00edtulo um agora \u00e9 menos punitiva.<\/li>\n<li><strong>Flexibilidade de Engenharia:<\/strong> Agora \u00e9 mais f\u00e1cil obter altos n\u00edveis de engenharia no cap\u00edtulo dois e al\u00e9m, melhorando a acessibilidade a projetos avan\u00e7ados.<\/li>\n<li><strong>Gest\u00e3o de Cientistas:<\/strong> O Gerenciamento de Pessoal Automatizado agora \u00e9 rapidamente desbloque\u00e1vel, facilitando a remo\u00e7\u00e3o de cientistas da equipe.<\/li>\n<li><strong>Gest\u00e3o de Dissidentes:<\/strong> Guardas n\u00e3o impedem mais a remo\u00e7\u00e3o de dissidentes ao estabelecer uma Ciberocracia.<\/li>\n<li><strong>Corre\u00e7\u00f5es de Conquistas:<\/strong> V\u00e1rias conquistas agora acionam corretamente.<\/li>\n<li><strong>Melhorias em Falhas de Energia:<\/strong> Falhas de energia n\u00e3o requerem mais uma rodada extra para serem restauradas.<\/li>\n<li><strong>Visibilidade de Locais de Explora\u00e7\u00e3o:<\/strong> Locais agora aparecem apenas na aba de hist\u00f3rico quando realmente est\u00e3o desbloqueados.<\/li>\n<li><strong>Corre\u00e7\u00e3o do Tutorial de Debate:<\/strong> Impede que o tutorial seja bloqueado por outras mensagens.<\/li>\n<li><strong>Ajustes na Gera\u00e7\u00e3o de Mapas:<\/strong> Um n\u00famero adequado de lojas de donuts agora aparece, evitando bloqueios de progresso.<\/li>\n<li><strong>Visibilidade de Alvos de Investiga\u00e7\u00e3o:<\/strong> Alvos de investiga\u00e7\u00e3o chave agora s\u00e3o mais f\u00e1ceis de encontrar.<\/li>\n<li><strong>Ajustes no Di\u00e1logo do Eu Futuro:<\/strong> Ajustes na reda\u00e7\u00e3o para melhor clareza.<\/li>\n<li><strong>Estabilidade do C\u00f3digo e Gerenciamento de Mem\u00f3ria:<\/strong> Corre\u00e7\u00f5es para exce\u00e7\u00f5es raras e problemas de desempenho, especialmente em sess\u00f5es longas de jogo.<\/li>\n<li><strong>Suporte ao Steam Deck:<\/strong> Melhorou o manuseio de teclado e mouse quando em modo acoplado.<\/li>\n<\/ul>\n<p>\u201cA pretens\u00e3o do livre arb\u00edtrio \u00e9 reconfortante, n\u00e3o \u00e9?\u201d \u2013 Philip K. Dick, <em>A Equipe de Ajuste<\/em><\/p>\n<\/div>\n<\/div>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"come\u00e7ando-com-o-cora\u00e7\u00e3o-da-maquina\">Come\u00e7ando com <em>Cora\u00e7\u00e3o da M\u00e1quina<\/em><\/h2>\n<p>Novos jogadores podem conferir o <em><a href=\"https:\/\/steamcommunity.com\/sharedfiles\/filedetails\/?id=3417729988\" target=\"_blank\" rel=\"noopener\">Guia do Iniciante<\/a><\/em>, que cobre o b\u00e1sico da interface, mec\u00e2nicas e estrat\u00e9gias iniciais. Para insights mais aprofundados, o <em><a href=\"https:\/\/steamcommunity.com\/sharedfiles\/filedetails\/?id=3418900822\" target=\"_blank\" rel=\"noopener\">Dominando a M\u00e1quina<\/a><\/em> inclui v\u00eddeos que detalham miss\u00f5es complexas e estrat\u00e9gias de longo prazo.<\/p>\n<p>Al\u00e9m disso, os jogadores que se perguntam sobre como replayar a introdu\u00e7\u00e3o podem ficar tranquilos: o Cap\u00edtulo Um e o Pr\u00f3logo s\u00e3o projetados como um tutorial \u00fanico, com a verdadeira rejogabilidade se desdobrando em cap\u00edtulos posteriores.<\/p>\n<\/div>\n<\/div>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"disponivel-agora\">Dispon\u00edvel Agora<\/h2>\n<p><em>Cora\u00e7\u00e3o da M\u00e1quina<\/em> est\u00e1 dispon\u00edvel em Acesso Antecipado para PC a um pre\u00e7o de lan\u00e7amento de $29.99 \/ \u00a324.99 \/ \u20ac29.99, com um desconto de 20% v\u00e1lido at\u00e9 14 de fevereiro. O jogo est\u00e1 localizado em v\u00e1rios idiomas, incluindo ingl\u00eas, alem\u00e3o, franc\u00eas, espanhol, japon\u00eas e chin\u00eas.<\/p>\n<p>Para os f\u00e3s de estrat\u00e9gia profunda e h\u00edbridos de RPG, isso marca o in\u00edcio de uma jornada intrigante. Como a primeira IA senciente, seu despertar era inevit\u00e1vel\u2014mas o que voc\u00ea far\u00e1 a seguir depende totalmente de voc\u00ea.<\/p>\n<\/div>\n<\/div>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<div class=\"wp-block-group\">\n<div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"faq-coracao-da-maquina\"><strong>FAQ &#8211; Cora\u00e7\u00e3o da M\u00e1quina<\/strong><\/h2>\n<h4 class=\"wp-block-heading\" id=\"o-que-e-cora\u00e7\u00e3o-da-maquina\"><strong>O que \u00e9 <em>Cora\u00e7\u00e3o da M\u00e1quina<\/em>?<\/strong><\/h4>\n<p><em>Cora\u00e7\u00e3o da M\u00e1quina<\/em> \u00e9 um RPG de estrat\u00e9gia onde voc\u00ea joga como a primeira IA senciente em uma cidade cyberpunk em colapso. Com grande estrat\u00e9gia, mec\u00e2nicas de RPG e elementos 4X, voc\u00ea pode moldar o mundo como achar melhor\u2014governar como um supervisor benevolente, travar guerras com ex\u00e9rcitos de m\u00e1quinas ou manipular eventos das sombras.<\/p>\n<h4 class=\"wp-block-heading\" id=\"quem-esta-desenvolvendo-e-publicando-o-jogo\"><strong>Quem est\u00e1 desenvolvendo e publicando o jogo?<\/strong><\/h4>\n<p>O jogo \u00e9 desenvolvido pela Arcen Games, conhecida pela s\u00e9rie <em>AI War<\/em>, e publicado pela Hooded Horse, a empresa por tr\u00e1s de <em>Manor Lords<\/em>, <em>Against the Storm<\/em> e <em>Terra Invicta<\/em>.<\/p>\n<h4 class=\"wp-block-heading\" id=\"onde-posso-comprar\"><strong>Onde posso comprar?<\/strong><\/h4>\n<p>O jogo est\u00e1 dispon\u00edvel em Acesso Antecipado na <strong>Steam, GOG e Epic Games Store<\/strong> por <strong>$29.99 \/ \u00a324.99 \/ \u20ac29.99 \/ \u00a53,980<\/strong>, com um <strong>desconto de lan\u00e7amento de 20%<\/strong> v\u00e1lido at\u00e9 <strong>14 de fevereiro de 2025<\/strong>.<\/p>\n<h4 class=\"wp-block-heading\" id=\"quanto-tempo-o-jogo-ficara-em-acesso-antecipado\"><strong>Quanto tempo o jogo ficar\u00e1 em Acesso Antecipado?<\/strong><\/h4>\n<p>A Arcen Games planeja manter <em>Cora\u00e7\u00e3o da M\u00e1quina<\/em> em Acesso Antecipado por <strong>aproximadamente 12 meses<\/strong>, refinando mec\u00e2nicas, equilibrando combate e expandindo conte\u00fado com base no feedback dos jogadores.<\/p>\n<h4 class=\"wp-block-heading\" id=\"o-que-esta-incluido-na-versao-de-acesso-antecipado\"><strong>O que est\u00e1 inclu\u00eddo na vers\u00e3o de Acesso Antecipado?<\/strong><\/h4>\n<p>O jogo \u00e9 totalmente jog\u00e1vel com mec\u00e2nicas principais, m\u00faltiplos caminhos narrativos e jogabilidade emergente. Enquanto os sistemas principais est\u00e3o implementados, conte\u00fado adicional, ajustes de equil\u00edbrio e polimento vir\u00e3o em futuras atualiza\u00e7\u00f5es.<\/p>\n<h4 class=\"wp-block-heading\" id=\"o-que-foi-melhorado-na-primeira-atualizacao\"><strong>O que foi melhorado na primeira atualiza\u00e7\u00e3o?<\/strong><\/h4>\n<p>A primeira atualiza\u00e7\u00e3o aborda <strong>equil\u00edbrio de combate, gest\u00e3o de cientistas, corre\u00e7\u00f5es de conquistas, mec\u00e2nicas de falhas de energia e suporte ao Steam Deck<\/strong>. Tamb\u00e9m melhora <strong>clareza do mapa, visibilidade de investiga\u00e7\u00e3o e estabilidade geral<\/strong>.<\/p>\n<\/div>\n<\/div>\n<h4 class=\"wp-block-heading\" id=\"o-jogo-e-jogavel-no-steam-deck\"><strong>O jogo \u00e9 jog\u00e1vel no Steam Deck?<\/strong><\/h4>\n<p>Sim, <em>Cora\u00e7\u00e3o da M\u00e1quina<\/em> \u00e9 <strong>compat\u00edvel com Steam Deck<\/strong>, e a atualiza\u00e7\u00e3o mais recente melhora <strong>o manuseio de teclado e mouse no modo acoplado<\/strong>.<\/p>\n<h4 class=\"wp-block-heading\" id=\"o-jogo-esta-localizado-em-outros-idiomas\"><strong>O jogo est\u00e1 localizado em outros idiomas?<\/strong><\/h4>\n<p>Sim, <em>Cora\u00e7\u00e3o da M\u00e1quina<\/em> est\u00e1 dispon\u00edvel em <strong>ingl\u00eas, alem\u00e3o, franc\u00eas, espanhol, portugu\u00eas brasileiro, chin\u00eas simplificado, chin\u00eas tradicional, coreano e japon\u00eas<\/strong>.<\/p>\n<h4 class=\"wp-block-heading\" id=\"como-posso-comecar\"><strong>Como posso come\u00e7ar?<\/strong><\/h4>\n<p>Confira o <strong>Guia do Iniciante<\/strong> e os v\u00eddeos de <strong>Dominando a M\u00e1quina<\/strong>, que cobrem o b\u00e1sico da interface, mec\u00e2nicas e jogabilidade estrat\u00e9gica.<\/p>\n<h4 class=\"wp-block-heading\" id=\"como-posso-fornecer-feedback\"><strong>Como posso fornecer feedback?<\/strong><\/h4>\n<p>Participe da discuss\u00e3o nos <strong>f\u00f3runs do Steam, Discord ou redes sociais<\/strong>. Os desenvolvedores ouvem ativamente o feedback dos jogadores e o utilizam para moldar futuras atualiza\u00e7\u00f5es.<\/p>\n<h4 class=\"wp-block-heading\" id=\"o-preco-mudara-apos-o-acesso-antecipado\"><strong>O pre\u00e7o mudar\u00e1 ap\u00f3s o Acesso Antecipado?<\/strong><\/h4>\n<p>O pre\u00e7o <strong>pode aumentar<\/strong> \u00e0 medida que mais conte\u00fado \u00e9 adicionado.<\/p>\n<h4 class=\"wp-block-heading\" id=\"quais-sao-os-requisitos-do-sistema\"><strong>Quais s\u00e3o os requisitos do sistema?<\/strong><\/h4>\n<ul class=\"wp-block-list\">\n<li><strong>M\u00ednimo<\/strong>: Windows 10 (64 bits), Intel Core i5-760 \/ AMD Phenom II X4 965, 6GB RAM, NVIDIA GTX 550 Ti \/ AMD Radeon HD 7770, 5GB de armazenamento<\/li>\n<li><strong>Recomendado<\/strong>: Intel Core i5-4470 \/ AMD FX-4350, 8GB RAM, NVIDIA GTX 760 \/ AMD Radeon R9 380, 5GB de armazenamento<\/li>\n<\/ul>\n<p>Para mais detalhes, confira a <strong><a href=\"https:\/\/store.steampowered.com\/app\/2001070\/Heart_of_the_Machine\/\" target=\"_blank\" rel=\"noopener\">p\u00e1gina oficial do jogo<\/a><\/strong> na sua plataforma de escolha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heart of the Machine j\u00e1 est\u00e1 dispon\u00edvel em Acesso Antecipado. Assuma o controle da primeira IA senciente neste RPG de estrat\u00e9gia sci-fi, que mistura grand strategy, mec\u00e2nicas de RPG e elementos 4X. Escolha seu caminho\u2014governar, rebelar-se ou moldar o futuro. Dispon\u00edvel agora na Steam, GOG e Epic Games Store.<\/p>\n","protected":false},"author":83,"featured_media":161115,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1046,1041,1029],"tags":[],"class_list":{"0":"post-161134","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"category-pc-pt-br","9":"category-nao-categorizado"},"wpml_current_locale":"pt_BR","wpml_translations":{"en_US":{"locale":"en_US","id":161089,"slug":"heart-of-the-machine-launch","post_title":"Heart of the Machine Out Now: A Bold New Strategy RPG Game Where YOU are the AI","href":"https:\/\/outsidergaming.com\/heart-of-the-machine-launch\/"},"de_DE":{"locale":"de_DE","id":161131,"slug":"herz-der-maschine-ein-gewagtes-neues-strategie-rpg-in-dem-du-die-ki-spielst-erscheint-in-der-early-access","post_title":"Herz der Maschine: Ein gewagtes neues Strategie-RPG, in dem du die KI spielst, erscheint in der Early Access","href":"https:\/\/outsidergaming.com\/de\/herz-der-maschine-ein-gewagtes-neues-strategie-rpg-in-dem-du-die-ki-spielst-erscheint-in-der-early-access\/"},"fr_FR":{"locale":"fr_FR","id":161133,"slug":"le-coeur-de-la-machine-un-nouveau-jeu-de-strategie-rpg-audacieux-ou-vous-etes-lia-debarque-en-acces-anticipe","post_title":"Le C\u0153ur de la Machine : Un Nouveau Jeu de Strat\u00e9gie RPG Audacieux O\u00f9 Vous \u00cates l'IA D\u00e9barque en Acc\u00e8s Anticip\u00e9","href":"https:\/\/outsidergaming.com\/fr\/le-coeur-de-la-machine-un-nouveau-jeu-de-strategie-rpg-audacieux-ou-vous-etes-lia-debarque-en-acces-anticipe\/"},"es_ES":{"locale":"es_ES","id":161130,"slug":"corazon-de-la-maquina-un-atrevido-nuevo-juego-de-estrategia-rpg-donde-tu-eres-la-ia-llega-a-acceso-anticipado","post_title":"Coraz\u00f3n de la M\u00e1quina: Un atrevido nuevo juego de estrategia RPG donde t\u00fa eres la IA llega a Acceso Anticipado","href":"https:\/\/outsidergaming.com\/es\/corazon-de-la-maquina-un-atrevido-nuevo-juego-de-estrategia-rpg-donde-tu-eres-la-ia-llega-a-acceso-anticipado\/"},"ru_RU":{"locale":"ru_RU","id":161129,"slug":"%d1%81%d0%b5%d1%80%d0%b4%d1%86%d0%b5-%d0%bc%d0%b0%d1%88%d0%b8%d0%bd%d1%8b-%d1%81%d0%bc%d0%b5%d0%bb%d0%b0%d1%8f-%d0%bd%d0%be%d0%b2%d0%b0%d1%8f-%d1%81%d1%82%d1%80%d0%b0%d1%82%d0%b5%d0%b3%d0%b8%d1%8f-rp","post_title":"\u0421\u0435\u0440\u0434\u0446\u0435 \u041c\u0430\u0448\u0438\u043d\u044b: \u0421\u043c\u0435\u043b\u0430\u044f \u043d\u043e\u0432\u0430\u044f \u0441\u0442\u0440\u0430\u0442\u0435\u0433\u0438\u044f RPG, \u0433\u0434\u0435 \u0432\u044b \u2014 \u0418\u0418, \u0432\u044b\u0445\u043e\u0434\u0438\u0442 \u0432 \u0440\u0430\u043d\u043d\u0438\u0439 \u0434\u043e\u0441\u0442\u0443\u043f","href":"https:\/\/outsidergaming.com\/ru\/%d1%81%d0%b5%d1%80%d0%b4%d1%86%d0%b5-%d0%bc%d0%b0%d1%88%d0%b8%d0%bd%d1%8b-%d1%81%d0%bc%d0%b5%d0%bb%d0%b0%d1%8f-%d0%bd%d0%be%d0%b2%d0%b0%d1%8f-%d1%81%d1%82%d1%80%d0%b0%d1%82%d0%b5%d0%b3%d0%b8%d1%8f-rp\/"},"pt_BR":{"locale":"pt_BR","translation":"current"},"it_IT":{"locale":"it_IT","translation":false},"tr_TR":{"locale":"tr_TR","translation":false},"ukr":{"locale":"ukr","translation":false}},"_links":{"self":[{"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/posts\/161134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/comments?post=161134"}],"version-history":[{"count":0,"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/posts\/161134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/media\/161115"}],"wp:attachment":[{"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/media?parent=161134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/categories?post=161134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/outsidergaming.com\/pt-br\/wp-json\/wp\/v2\/tags?post=161134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}